{"id":6119,"date":"2019-09-23T19:03:13","date_gmt":"2019-09-23T19:03:13","guid":{"rendered":"https:\/\/www.contugas.com.pe\/blog\/\/?p=6119"},"modified":"2022-11-29T14:31:41","modified_gmt":"2022-11-29T19:31:41","slug":"cambiateyaagnv","status":"publish","type":"post","link":"https:\/\/www.contugas.com.pe\/blog\/index.php\/cambiateyaagnv\/","title":{"rendered":"C\u00e1mbiate Ya a GNV"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6457\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV.jpg 1920w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-300x169.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1024x576.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-768x432.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6458\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1.jpg 1200w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-1-800x800.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6459\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-scaled.jpg\" alt=\"\" width=\"2560\" height=\"2560\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-scaled.jpg 2560w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-1536x1536.jpg 1536w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-2048x2048.jpg 2048w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/POST-9-800x800.jpg 800w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6461\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2.jpg 1200w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-2-800x800.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6462\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3.jpg 1200w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-3-800x800.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6463\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4.jpg 1200w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-4-800x800.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6464\" src=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5.jpg\" alt=\"\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5.jpg 1200w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-300x300.jpg 300w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-1024x1024.jpg 1024w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-150x150.jpg 150w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-768x768.jpg 768w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-100x100.jpg 100w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-140x140.jpg 140w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-500x500.jpg 500w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-350x350.jpg 350w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-1000x1000.jpg 1000w, https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/Post-5-800x800.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":6457,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[47],"class_list":{"0":"post-6119","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-campanas","8":"tag-ahorrognv"},"better_featured_image":{"id":6457,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1920,"height":1080,"file":"2019\/09\/FLYER-GNV.jpg","sizes":{"medium":{"file":"FLYER-GNV-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-300x169.jpg"},"large":{"file":"FLYER-GNV-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1024x576.jpg"},"thumbnail":{"file":"FLYER-GNV-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-150x150.jpg"},"medium_large":{"file":"FLYER-GNV-768x432.jpg","width":768,"height":432,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-768x432.jpg"},"1536x1536":{"file":"FLYER-GNV-1536x864.jpg","width":1536,"height":864,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1536x864.jpg"},"portfolio-thumb":{"file":"FLYER-GNV-600x403.jpg","width":600,"height":403,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-600x403.jpg"},"portfolio-thumb_small":{"file":"FLYER-GNV-400x269.jpg","width":400,"height":269,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-400x269.jpg"},"portfolio-widget":{"file":"FLYER-GNV-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-100x100.jpg"},"nectar_small_square":{"file":"FLYER-GNV-140x140.jpg","width":140,"height":140,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-140x140.jpg"},"wide":{"file":"FLYER-GNV-1000x500.jpg","width":1000,"height":500,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1000x500.jpg"},"wide_small":{"file":"FLYER-GNV-670x335.jpg","width":670,"height":335,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-670x335.jpg"},"regular":{"file":"FLYER-GNV-500x500.jpg","width":500,"height":500,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-500x500.jpg"},"regular_small":{"file":"FLYER-GNV-350x350.jpg","width":350,"height":350,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-350x350.jpg"},"tall":{"file":"FLYER-GNV-500x1000.jpg","width":500,"height":1000,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-500x1000.jpg"},"wide_tall":{"file":"FLYER-GNV-1000x1000.jpg","width":1000,"height":1000,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1000x1000.jpg"},"wide_photography":{"file":"FLYER-GNV-900x600.jpg","width":900,"height":600,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-900x600.jpg"},"large_featured":{"file":"FLYER-GNV-1700x700.jpg","width":1700,"height":700,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-1700x700.jpg"},"medium_featured":{"file":"FLYER-GNV-800x800.jpg","width":800,"height":800,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-800x800.jpg"},"img_post":{"file":"FLYER-GNV-365x250.jpg","width":365,"height":250,"mime-type":"image\/jpeg","source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV-365x250.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":6119,"source_url":"https:\/\/www.contugas.com.pe\/blog\/wp-content\/uploads\/2019\/09\/FLYER-GNV.jpg"},"_links":{"self":[{"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6119"}],"collection":[{"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=6119"}],"version-history":[{"count":7,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6119\/revisions"}],"predecessor-version":[{"id":6466,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6119\/revisions\/6466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/media\/6457"}],"wp:attachment":[{"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=6119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=6119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.contugas.com.pe\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=6119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}